
{"id":416452,"date":"2025-09-10T16:15:06","date_gmt":"2025-09-10T19:15:06","guid":{"rendered":"https:\/\/mkt.estrategia.com\/concursos\/?page_id=416452"},"modified":"2025-09-11T17:33:09","modified_gmt":"2025-09-11T20:33:09","slug":"promo-estrategia-oportunidades","status":"publish","type":"page","link":"https:\/\/mkt.estrategia.com\/concursos\/promo-estrategia-oportunidades\/","title":{"rendered":"[Campanha Estrat\u00e9gia Oportunidades] Produtos em promo\u00e7\u00e3o!"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Motivos&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; background_color=&#8221;#1e1042&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;138deg&#8221; background_color_gradient_stops=&#8221;#000730 36%|rgba(233,186,66,0.19) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/mkt.estrategia.com\/concursos\/wp-content\/uploads\/sites\/2\/2025\/01\/coruja-scaled.webp&#8221; min_height=&#8221;310.6px&#8221; display_conditions=&#8221;W3siaWQiOiJhZDg5ZGY0Zi0xZTlmLTQxZDQtYTgzZi0wMzllMTI4MDdkOGYiLCJjb25kaXRpb24iOiJ1c2VyUm9sZSIsImNvbmRpdGlvblNldHRpbmdzIjp7InVzZXJSb2xlRGlzcGxheSI6ImlzIiwidXNlclJvbGVzIjpbeyJsYWJlbCI6IkFkbWluaXN0cmF0b3IiLCJ2YWx1ZSI6ImFkbWluaXN0cmF0b3IifV0sInVzZXJJZHMiOiJVc2VyIElEcyBzZXBhcmF0ZWQgYnkgY29tbWFzIiwiYWRtaW5MYWJlbCI6IlVzZXIgUm9sZSIsImVuYWJsZUNvbmRpdGlvbiI6Im9mZiJ9LCJvcGVyYXRvciI6Ik9SIn1d&#8221; custom_margin=&#8221;0px|0px|0px|0px|false|false&#8221; custom_padding=&#8221;19px|0px|0px|0px|false|false&#8221; animation_style=&#8221;slide&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_css_before_last_edited=&#8221;on|desktop&#8221;][et_pb_row admin_label=&#8221;LOGO COM LINK&#8221; module_id=&#8221;head&#8221; _builder_version=&#8221;4.27.0&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;17px||0px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code admin_label=&#8221;LOGO SVG ESTRAT\u00c9GIA CONCURSOS&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<img src=\"https:\/\/mkt.estrategia.com\/concursos\/wp-content\/uploads\/sites\/2\/2025\/07\/logo_estrategia_branco.svg\" width=\"151\" height=\"41\" alt=\"Logo\" decoding=\"async\" fetchpriority=\"high\" \/><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;1280px&#8221; custom_padding=&#8221;15px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;9px&#8221; text_line_height=&#8221;1em&#8221; header_font=&#8221;Times New Roman|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;55px&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;88%&#8221; max_width_tablet=&#8221;94%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;122px&#8221; height=&#8221;100px&#8221; max_height=&#8221;100px&#8221; custom_margin=&#8221;-18px|3px|55px|3px|false|true&#8221; custom_margin_tablet=&#8221;0px|3px|53px|3px|false|true&#8221; custom_margin_phone=&#8221;0px|3px|0px|3px|false|true&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;23px||63px|||&#8221; text_text_color_tablet=&#8221;gcid-a906ec42-9a65-410a-967e-8598e0be37e9&#8243; text_text_color_phone=&#8221;gcid-a906ec42-9a65-410a-967e-8598e0be37e9&#8243; text_text_color_last_edited=&#8221;on|desktop&#8221; text_font_size_tablet=&#8221;9px&#8221; text_font_size_phone=&#8221;9px&#8221; header_font_size_tablet=&#8221;55px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover_enabled=&#8221;on|desktop&#8221; text_text_color__hover=&#8221;#b17c36&#8243;]<\/p>\n<h1><span style=\"color: #ffffff;\">EU VOU PERDER O MEU EMPREGO?<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;_initial&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;9px&#8221; text_line_height=&#8221;1em&#8221; header_font=&#8221;Times New Roman|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;55px&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;88%&#8221; max_width_tablet=&#8221;94%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; min_height=&#8221;82px&#8221; height=&#8221;100px&#8221; max_height=&#8221;100px&#8221; custom_margin=&#8221;-65px|3px||3px|false|true&#8221; custom_margin_tablet=&#8221;0px|3px|53px|3px|false|true&#8221; custom_margin_phone=&#8221;50px|3px|100px|3px|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px||1px|||&#8221; text_text_color_tablet=&#8221;gcid-a906ec42-9a65-410a-967e-8598e0be37e9&#8243; text_text_color_phone=&#8221;gcid-a906ec42-9a65-410a-967e-8598e0be37e9&#8243; text_text_color_last_edited=&#8221;on|desktop&#8221; text_font_size_tablet=&#8221;9px&#8221; text_font_size_phone=&#8221;9px&#8221; header_font_size_tablet=&#8221;55px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; text_text_color__hover_enabled=&#8221;on|desktop&#8221; text_text_color__hover=&#8221;#b17c36&#8243;]<\/p>\n<h1><span style=\"color: #ffd700; font-size: x-large;\">Certamente, voc\u00ea j\u00e1 conviveu com essa d\u00favida.<\/span><\/h1>\n<h1><span style=\"color: #ffffff; font-size: x-large;\">Mas, voc\u00ea n\u00e3o est\u00e1 sozinho \u2014 e uma nova oportunidade pode estar apenas come\u00e7ando.<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;off|phone&#8221; max_width=&#8221;2560px&#8221; custom_margin=&#8221;0px|0px||0px|false|false&#8221; custom_margin_tablet=&#8221;0px|0px||0px|false|false&#8221; custom_margin_phone=&#8221;50px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;15px|71px||71px|false|true&#8221; custom_padding_tablet=&#8221;15px|71px||71px|false|true&#8221; custom_padding_phone=&#8221;50px|23px||23px|false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; border_radii=&#8221;on|20px|20px|20px|20px&#8221; admin_label=&#8221;Imagem via C\u00f3digo&#8221;]<img <!-- [et_pb_line_break_holder] -->    src=&#8221;https:\/\/mkt.estrategia.com\/concursos\/wp-content\/uploads\/sites\/2\/2025\/09\/noticia-Itau-768&#215;267-1.webp&#8221; <!-- [et_pb_line_break_holder] -->    width=&#8221;768&#8243; height=&#8221;267&#8243; <!-- [et_pb_line_break_holder] -->    alt=&#8221;Demiss\u00e3o em massa Ita\u00fa&#8221; <!-- [et_pb_line_break_holder] -->    decoding=&#8221;async&#8221; <!-- [et_pb_line_break_holder] -->    fetchpriority=&#8221;high&#8221;><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;25px&#8221; header_font=&#8221;Poppins Light|300|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;90%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;9px||16px||false|false&#8221; custom_margin_tablet=&#8221;9px||16px||false|false&#8221; custom_margin_phone=&#8221;50px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; module_alignment_tablet=&#8221;&#8221; module_alignment_phone=&#8221;center&#8221; module_alignment_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><\/h1>\n<h1><\/h1>\n<h1 style=\"text-align: left;\">\u2611 No dia 8 de setembro de 2025, o Ita\u00fa Unibanco realizou <span style=\"color: #ffd700;\">desligamentos em funcion\u00e1rios em regime remoto ou h\u00edbrido<\/span>, ap\u00f3s uma &#8220;revis\u00e3o criteriosa de condutas relacionadas ao trabalho remoto e registro de jornada&#8221;;<\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: left;\">\u2611 O Sindicato estimou cerca de <span style=\"color: #ffd700;\">1.000 demiss\u00f5es<\/span>, enquanto relatos apontam que o banco considerou demitir at\u00e9 <span style=\"color: #ffd700;\">2.000 funcion\u00e1rios<\/span> inicialmente.<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00062b&#8221; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;23px|||||&#8221; custom_padding_tablet=&#8221;23px|||||&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_5,3_5,1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1454px&#8221; custom_margin=&#8221;||||true|false&#8221; custom_padding=&#8221;14px|0px|14px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;29px||29px|20px|true|false&#8221; custom_padding_tablet=&#8221;29px||29px|20px|true|false&#8221; custom_padding_phone=&#8221;29px||29px|20px|true|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2><span class=%22vendas-cnu-25%22>Um dos melhores concursos de <strong>n\u00edvel m\u00e9dio est\u00e1 com edital publicado e voc\u00ea pode receber sal\u00e1rios de R$ 6 mil iniciais<\/strong><br \/><\/span><\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;32px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||13px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #ffd700;\"><strong>N\u00e3o fa\u00e7a parte desse tipo de estat\u00edstica.<\/strong><\/span><\/h2>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<h2><strong>Conhe\u00e7a o Estrat\u00e9gia Concursos: sua ponte para um futuro seguro no mundo do Concursos P\u00fablicos.<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1200px&#8221; custom_margin=&#8221;30px|auto|30px|auto|false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#12284d 0%|#000621 100%&#8221; custom_padding=&#8221;30px|10px|30px|10px|true|true&#8221; custom_css_main_element=&#8221;backdrop-filter: Blur(4px);&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f4c529&#8243; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(77,86,112,0.52)&#8221;][et_pb_icon font_icon=&#8221;&#xf14a;||fa||900&#8243; icon_color=&#8221;#f7e3ac&#8221; icon_width=&#8221;40px&#8221; align=&#8221;left&#8221; align_tablet=&#8221;left&#8221; align_phone=&#8221;left&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_text content_tablet=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova<br \/>no exame do CFC!<\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova no exame do CFC!<\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Light||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.5em&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;20px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_4_font=&#8221;Poppins Light||||||||&#8221; header_4_text_color=&#8221;#f5e7e7&#8243; header_4_font_size=&#8221;16px&#8221; header_4_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><b>Curso completo que mais aprova alunos<\/b><b><br \/><\/b><span style=\"font-weight: 400;\"> 7 a cada 10 aprovados em concursos federais estudaram com o Estrat\u00e9gia.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#12284d 0%|#000621 100%&#8221; custom_padding=&#8221;30px|10px|30px|10px|true|true&#8221; custom_css_main_element=&#8221;backdrop-filter: Blur(4px);&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f4c529&#8243; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(77,86,112,0.52)&#8221;][et_pb_icon font_icon=&#8221;&#xf14a;||fa||900&#8243; icon_color=&#8221;#f7e3ac&#8221; icon_width=&#8221;40px&#8221; align=&#8221;left&#8221; align_tablet=&#8221;left&#8221; align_phone=&#8221;left&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_text content_tablet=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova<br \/>no exame do CFC!<\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova no exame do CFC!<\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Light||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.5em&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;20px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_4_font=&#8221;Poppins Light||||||||&#8221; header_4_text_color=&#8221;#f5e7e7&#8243; header_4_font_size=&#8221;16px&#8221; header_4_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\"><b>Melhores professores do pa\u00eds<\/b><b><br \/><\/b> Time de especialistas em todas as disciplinas exigidas nos mais diversos concursos do pa\u00eds.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#12284d 0%|#000621 100%&#8221; custom_padding=&#8221;30px|10px|30px|10px|true|true&#8221; custom_css_main_element=&#8221;backdrop-filter: Blur(4px);&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f4c529&#8243; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(77,86,112,0.52)&#8221;][et_pb_icon font_icon=&#8221;&#xf14a;||fa||900&#8243; icon_color=&#8221;#f7e3ac&#8221; icon_width=&#8221;40px&#8221; align=&#8221;left&#8221; align_tablet=&#8221;left&#8221; align_phone=&#8221;left&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_text content_tablet=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova<br \/>no exame do CFC!<\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova no exame do CFC!<\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Light||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.5em&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;20px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_4_font=&#8221;Poppins Light||||||||&#8221; header_4_text_color=&#8221;#f5e7e7&#8243; header_4_font_size=&#8221;16px&#8221; header_4_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><b>Ferramentas exclusivas que aceleram o aprendizado<\/b><b><br \/><\/b><span style=\"font-weight: 400;\"> PDFs completos, videoaulas objetivas, quest\u00f5es comentadas e resumos estrat\u00e9gicos.<\/span><\/h4>\n<p>[\/et_pb_text][et_pb_image _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;1200px&#8221; custom_margin=&#8221;30px|auto|30px|auto|false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#12284d 0%|#000621 100%&#8221; custom_padding=&#8221;30px|10px|30px|10px|true|true&#8221; custom_css_main_element=&#8221;backdrop-filter: Blur(4px);&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f4c529&#8243; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(77,86,112,0.52)&#8221;][et_pb_icon font_icon=&#8221;&#xf14a;||fa||900&#8243; icon_color=&#8221;#f7e3ac&#8221; icon_width=&#8221;40px&#8221; align=&#8221;left&#8221; align_tablet=&#8221;left&#8221; align_phone=&#8221;left&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_text content_tablet=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova<br \/>no exame do CFC!<\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova no exame do CFC!<\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Light||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.5em&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;20px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_4_font=&#8221;Poppins Light||||||||&#8221; header_4_text_color=&#8221;#f5e7e7&#8243; header_4_font_size=&#8221;16px&#8221; header_4_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\"><b>Sua ponte para a ESTABILIDADE<\/b><b><br \/><\/b>Em meio \u00e0 incerteza do mercado de trabalho, os concursos p\u00fablicos oferecem <strong>seguran\u00e7a, remunera\u00e7\u00e3o atrativa e benef\u00edcios consistentes<\/strong>. O Estrat\u00e9gia \u00e9 a ponte que conecta voc\u00ea a essa estabilidade, com a prepara\u00e7\u00e3o completa para conquistar sua aprova\u00e7\u00e3o.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#12284d 0%|#000621 100%&#8221; custom_padding=&#8221;30px|10px|30px|10px|true|true&#8221; custom_css_main_element=&#8221;backdrop-filter: Blur(4px);&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#f4c529&#8243; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(77,86,112,0.52)&#8221;][et_pb_icon font_icon=&#8221;&#xf14a;||fa||900&#8243; icon_color=&#8221;#f7e3ac&#8221; icon_width=&#8221;40px&#8221; align=&#8221;left&#8221; align_tablet=&#8221;left&#8221; align_phone=&#8221;left&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_icon][et_pb_text content_tablet=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova<br \/>no exame do CFC!<\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>Garanta sua aprova\u00e7\u00e3o com o curso que aprova no exame do CFC!<\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Light||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.5em&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;20px&#8221; header_2_line_height=&#8221;1.4em&#8221; header_4_font=&#8221;Poppins Light||||||||&#8221; header_4_text_color=&#8221;#f5e7e7&#8243; header_4_font_size=&#8221;16px&#8221; header_4_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><b>Garantia de atualiza\u00e7\u00e3o<\/b><b><br \/><\/b><span style=\"font-weight: 400;\"> Seja quando for a prova, seu material ser\u00e1 100% atualizado at\u00e9 a data do concurso.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;center&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;25px&#8221; header_2_line_height=&#8221;1.3em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: #ffffff;\">Fa\u00e7a o download do nosso <strong>E-book de Oportunidades<\/strong> e veja a que mais se enquadra no seu sonho!<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/09\/05142349\/ec_ebook_concursos_set_25.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Baixar E-book&#8221; button_alignment=&#8221;center&#8221; button_alignment_tablet=&#8221;left&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;30px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#071882&#8243; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;#FFFFFF&#8221; button_border_radius=&#8221;8px&#8221; button_font=&#8221;Poppins Bold||||||||&#8221; button_icon=&#8221;&#xe07a;||divi||400&#8243; button_icon_color=&#8221;#FFFFFF&#8221; custom_padding_tablet=&#8221;11px|70px|11px|70px|true|false&#8221; custom_padding_phone=&#8221;11px|30px|11px|30px|true|true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; button_text_size_last_edited=&#8221;off|desktop&#8221; button_text_color_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(44,213,142,0.38)&#8221; button_bg_color__hover_enabled=&#8221;off|desktop&#8221; button_bg_use_color_gradient__hover=&#8221;on&#8221; custom_padding__hover=&#8221;5px|40px|5px|40px|true|true&#8221; button_bg_color__hover=&#8221;#936605&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;off|desktop&#8221; button_text_color__hover=&#8221;#FFFFFF&#8221; button_bg_color_gradient_stops__hover=&#8221;#efe1ae 0%|#ad9e69 35%|#ad9e69 65%|rgba(239, 225, 174, 1) 100%&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2><span class=%22vendas-cnu-25%22>Um dos melhores concursos de <strong>n\u00edvel m\u00e9dio est\u00e1 com edital publicado e voc\u00ea pode receber sal\u00e1rios de R$ 6 mil iniciais<\/strong><br \/><\/span><\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;32px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||13px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #0a0a0a; font-size: xx-large;\"><strong>Veja as carreiras que podem <span style=\"background-color:#FFD700;\">mudar o seu futuro<\/span> em 2025\/2026<\/strong><\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Fiscal&#8221; image_icon_width=&#8221;62%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 Sefaz SP<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 Sefaz DF<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 Sefaz PA<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 Sefaz RN<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 Sefaz PR<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 ISS Manaus<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 ISS Niter\u00f3i<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;  Policial &#8221; image_icon_width=&#8221;62%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udee1\ufe0f PF<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udee1\ufe0f PF Administrativo<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udee1\ufe0f PRF<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udee1\ufe0f PMDF<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udee1\ufe0f PM CE<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udee1\ufe0f PM ES<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udee1\ufe0f PM TO<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Educa\u00e7\u00e3o &#8221; image_icon_width=&#8221;62%&#8221; title_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcda SEED AP<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcda SEDUC PA<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcda SEDUC SE<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcda SEDUC GO<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcda SEDUC AL<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcda Seduc PI (efetivos)<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcda SEDF (efetivos)<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Controle &#8221; image_icon_width=&#8221;62%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 CGM Manaus<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 TCE RJ<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 TCE PB<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 TCE MA<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 TCE RN<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 TCE MG<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udcd2 TCE SC<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Legislativa&#8221; image_icon_width=&#8221;62%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfdb\ufe0f ALE ES<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfdb\ufe0f ALE RR<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfdb\ufe0f ALE RO<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfdb\ufe0f ALEGO<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfdb\ufe0f AL MS<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfdb\ufe0f ALERJ<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfdb\ufe0f ALE AM<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Banc\u00e1rio &#8221; image_icon_width=&#8221;62%&#8221; title_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfe6 Banco do Brasil<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfe6 Banrisul<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfe6 CVM<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Tribunais&#8221; image_icon_width=&#8221;62%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u2696\ufe0f TJ RJ<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u2696\ufe0f TRT SP<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u2696\ufe0f TRE TO<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u2696\ufe0f TRT MT<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u2696\ufe0f TJ CE<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u2696\ufe0f TJMG<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u2696\ufe0f TJ PB<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Sa\u00fade&#8221; image_icon_width=&#8221;62%&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;0.9em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83e\ude7a SESAP RN<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83e\ude7a SES SE<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83e\ude7a SMS BH<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83e\ude7a Hemocentro DF<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83e\ude7a SESA ES<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83e\ude7a SESA AP<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83e\ude7a SESAPI<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;22px|23px|22px|23px|true|true&#8221; border_radii=&#8221;on|16px|16px|16px|16px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#0c0000&#8243; box_shadow_style=&#8221;preset4&#8243; box_shadow_color=&#8221;#200359&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Prefeituras&#8221; image_icon_width=&#8221;62%&#8221; title_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Poppins Medium||||||||&#8221; body_text_align=&#8221;left&#8221; body_line_height=&#8221;1.2em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfd8\ufe0f Prefeitura de Juazeiro (BA)<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfd8\ufe0f Prefeitura de Vila Velha (ES)<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfd8\ufe0f Prefeitura de Barra de S\u00e3o Francisco (ES)<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfd8\ufe0f Prefeitura de Araguari (MG)<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfd8\ufe0f Prefeitura de Campina Grande (PB)<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfd8\ufe0f Prefeitura de Curitiba (PR)<\/span><\/p>\n<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83c\udfd8\ufe0f Prefeitura de Joinville (SC)<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#131313&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#00001e 1%|#0c1b3b 100%&#8221; background_enable_image=&#8221;off&#8221; custom_margin=&#8221;-34px|||||&#8221; custom_padding=&#8221;23px|||||&#8221; custom_padding_tablet=&#8221;23px|||||&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2><span class=%22vendas-cnu-25%22>Um dos melhores concursos de <strong>n\u00edvel m\u00e9dio est\u00e1 com edital publicado e voc\u00ea pode receber sal\u00e1rios de R$ 6 mil iniciais<\/strong><br \/><\/span><\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;32px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||13px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Agora \u00e9 a sua vez: transforme esse momento em impulso para uma carreira p\u00fablica!<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;80deg&#8221; background_color_gradient_stops=&#8221;rgba(67,68,114,0.65) 4%|rgba(29,68,102,0.95) 97%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/mkt.estrategia.com\/concursos\/wp-content\/uploads\/sites\/2\/2025\/02\/Gen-3-Alpha-Turbo-943662386-looping-Cropped-5375255_27-M-5.mp4.webp&#8221; parallax=&#8221;on&#8221; transform_translate_linked=&#8221;off&#8221; width_tablet=&#8221;85%&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;1280px&#8221; custom_margin=&#8221;20px|auto||auto|false|false&#8221; custom_margin_tablet=&#8221;20px|auto||auto|false|false&#8221; custom_margin_phone=&#8221;0px|auto||auto|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;15px|60px|15px|60px|true|true&#8221; custom_padding_tablet=&#8221;15px|60px|15px|60px|true|true&#8221; custom_padding_phone=&#8221;15px|30px|15px|30px|true|true&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#0054bc&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe073;||divi||400&#8243; icon_color=&#8221;#fbd982&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;38px&#8221; content_max_width=&#8221;643px&#8221; content_tablet=&#8221;<\/p>\n<p><strong>B\u00d4NUS<\/strong>: 3 MENTORIAS COM NUBIA OLIVEIRA<\/p>\n<p>&#8221; content_phone=&#8221;<\/p>\n<p><strong>B\u00d4NUS<\/strong>: 3 MENTORIAS COM NUBIA OLIVEIRA<\/p>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Bold||||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;27px&#8221; body_font=&#8221;Poppins Regular||||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_font_size=&#8221;19px&#8221; body_line_height=&#8221;1.5em&#8221; image_icon_custom_margin=&#8221;|||0px|false|false&#8221; image_icon_custom_margin_tablet=&#8221;|||100px|false|false&#8221; image_icon_custom_margin_phone=&#8221;|||10px|false|false&#8221; image_icon_custom_margin_last_edited=&#8221;on|phone&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||2px||false|false&#8221; custom_margin_tablet=&#8221;||20px||false|false&#8221; custom_margin_phone=&#8221;||0px|0px|false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;15px|20px|15px|20px|true|true&#8221; custom_padding_tablet=&#8221;15px|20px|15px|20px|true|true&#8221; custom_padding_phone=&#8221;15px|0px|15px|0px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; border_color_all=&#8221;#594f2f&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"color: #ffffff;\"><strong>ALERTA CUPOM<\/strong>: USE O CUPOM <strong><span style=\"color: #ffd700;\">#DEMITIDO30<\/span><\/strong> E GANHE <strong>30% DE DESCONTO<\/strong> EM QUALQUER PACOTE OU NA ASSINATURA PREMIUM.<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #ffffff;\"> PROMO\u00c7\u00c3O V\u00c1LIDA AT\u00c9 <strong>15\/09<\/strong><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_margin=&#8221;30px|auto|30px|auto|false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O que vem no <strong>Pacote Completo?<\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2><\/h2>\n<h2>O que voc\u00ea ter\u00e1 em m\u00e3os com os<br \/><strong>Pacotes Completos?<\/strong><\/h2>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||13px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #e1b459;\">O que te oferecemos nos<\/span><br \/><span style=\"color: #e1b459;\"><strong>Pacotes Completos?<\/strong><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> <span style=\"font-weight: 400;\">PDFs e videoaulas completas para concursos espec\u00edficos<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> Quest\u00f5es Comentadas<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> Resumos e mapas mentais\u00a0<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> Trilhas Estrat\u00e9gicas com plano de estudos\u00a0<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> PDF Simplificado[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> PDF Marca\u00e7\u00e3o dos Aprovados[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714 <\/span>F\u00f3rum de D\u00favidas<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#e1b459 0%|#bc954b 100%&#8221; custom_padding=&#8221;30px|10px|30px|10px|true|true&#8221; custom_css_main_element=&#8221;backdrop-filter: Blur(4px);&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#390a0d&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(77,86,112,0.52)&#8221;][et_pb_image _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;33px&#8221; header_2_letter_spacing=&#8221;2px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||0px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #00062b;\"><strong>TODOS OS PACOTES DO SITE<\/strong><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#00062b&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;67%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;11px||4px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Medium|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;66px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||0px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;||21px|||&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fc0000;\">30% OFF<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.estrategiaconcursos.com.br\/pacotes\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;assine agora&#8221; button_alignment=&#8221;center&#8221; button_text_tablet=&#8221;SIM! QUERO MINHA FARDA EM 2025&#8243; button_text_phone=&#8221;QUERO MINHA FARDA EM 2025&#8243; button_text_last_edited=&#8221;off|desktop&#8221; button_alignment_tablet=&#8221;left&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#e9cc81&#8243; button_bg_use_color_gradient=&#8221;on&#8221; button_bg_color_gradient_direction=&#8221;90deg&#8221; button_bg_color_gradient_direction_radial=&#8221;top&#8221; button_bg_color_gradient_stops=&#8221;#00062b 0%|#002089 100%&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#e2d83f&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;Poppins Medium|500||on|on|||RGBA(255,255,255,0)|&#8221; button_icon=&#8221;&#x26;||divi||400&#8243; custom_margin=&#8221;10px||||false|false&#8221; custom_margin_tablet=&#8221;10px||||false|false&#8221; custom_margin_phone=&#8221;0px||20px||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;10px|50px|10px|50px|true|true&#8221; custom_padding_tablet=&#8221;11px|70px|11px|70px|true|false&#8221; custom_padding_phone=&#8221;11px|30px|11px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; button_text_size_tablet=&#8221;&#8221; button_text_size_phone=&#8221;&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|desktop&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|desktop&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;rgba(255,255,255,0.31)&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||50px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_margin=&#8221;30px|auto|30px|auto|false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O que vem no <strong>Pacote Completo?<\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>O que voc\u00ea ter\u00e1 em m\u00e3os com as<br \/><strong>Assinaturas?<\/strong><\/h2>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||13px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #e1b459;\">O que te oferecemos nas<\/span><br \/><span style=\"color: #e1b459;\"><strong>Assinaturas?<\/strong><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> <span style=\"font-weight: 400;\">Com as Assinaturas, voc\u00ea n\u00e3o precisa comprar um pacote sempre que se interessar por um concurso<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Roboto Bold||||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;35px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Poppins Light||||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#f4f4f4&#8243; header_2_font_size=&#8221;18px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||2px||false|false&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;35px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;20px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #fef9da;\">\u2714<\/span> Tenha todas as ferramentas dos Pacotes, al\u00e9m de outras exclusivas, e se prepare para <strong>TODOS os concursos<\/strong>!<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#e1b459 0%|#bc954b 100%&#8221; custom_padding=&#8221;30px|10px|30px|10px|true|true&#8221; custom_css_main_element=&#8221;backdrop-filter: Blur(4px);&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#390a0d&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;off|desktop&#8221; box_shadow_color__hover_enabled=&#8221;on|hover&#8221; box_shadow_color__hover=&#8221;rgba(77,86,112,0.52)&#8221;][et_pb_image _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;33px&#8221; header_2_letter_spacing=&#8221;2px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||0px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #00062b;\"><strong>ASSINATURA PREMIUM<\/strong><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#00062b&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;67%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;11px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text content_tablet=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2>O maior concurso p\u00fablico de 2025 est\u00e1 com edital publicado, <span class=%22vendas-cnu-25%22><strong>com 3.652 vagas em 36 \u00f3rg\u00e3os p\u00fablicos e<\/strong><\/span><strong> <span class=%22vendas-cnu-25%22>sal\u00e1rios de at\u00e9 R$ 16 mil iniciais<\/span><\/strong><\/h2>\n<p>&#8221; content_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;Poppins Medium|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;66px&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;15px||0px||false|false&#8221; custom_margin_tablet=&#8221;40px||5px||false|false&#8221; custom_margin_phone=&#8221;0px||5px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;||28px|||&#8221; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;center&#8221; header_text_align_last_edited=&#8221;on|phone&#8221; header_2_text_align_tablet=&#8221;left&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;\/*adi\u00e7\u00e3o de gradiente em titulos *\/||.gradiente {||  background: linear-gradient(to right, #cbb054, #eadc95);||  -webkit-background-clip: text;||  -webkit-text-fill-color: transparent;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span style=\"color: #ff0000;\">30% OFF<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;assine agora&#8221; button_alignment=&#8221;center&#8221; button_text_tablet=&#8221;SIM! QUERO MINHA FARDA EM 2025&#8243; button_text_phone=&#8221;QUERO MINHA FARDA EM 2025&#8243; button_text_last_edited=&#8221;off|desktop&#8221; button_alignment_tablet=&#8221;left&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#e9cc81&#8243; button_bg_use_color_gradient=&#8221;on&#8221; button_bg_color_gradient_direction=&#8221;90deg&#8221; button_bg_color_gradient_direction_radial=&#8221;top&#8221; button_bg_color_gradient_stops=&#8221;#00062b 0%|#002089 100%&#8221; button_border_width=&#8221;1px&#8221; button_border_color=&#8221;#e2d83f&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;Poppins Medium|500||on|on|||RGBA(255,255,255,0)|&#8221; button_icon=&#8221;&#x26;||divi||400&#8243; custom_margin=&#8221;10px||||false|false&#8221; custom_margin_tablet=&#8221;10px||||false|false&#8221; custom_margin_phone=&#8221;0px||20px||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;10px|50px|10px|50px|true|true&#8221; custom_padding_tablet=&#8221;11px|70px|11px|70px|true|false&#8221; custom_padding_phone=&#8221;11px|30px|11px|30px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; button_text_size_tablet=&#8221;&#8221; button_text_size_phone=&#8221;&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; transform_styles__hover_enabled=&#8221;on|desktop&#8221; transform_scale__hover=&#8221;105%|105%&#8221; transform_scale__hover_enabled=&#8221;on|desktop&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_countdown_timer title=&#8221;Esta oferta expira em&#8221; date_time=&#8221;2025-09-15 23:59&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Poppins Regular|||on|||||&#8221; header_font_size=&#8221;27px&#8221; numbers_font=&#8221;Poppins Medium||||||||&#8221; numbers_font_size=&#8221;46px&#8221; label_font=&#8221;||||||||&#8221; label_font_size=&#8221;15px&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;9px||15px|||&#8221; header_font_size_tablet=&#8221;27px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; numbers_font_size_tablet=&#8221;46px&#8221; numbers_font_size_phone=&#8221;30px&#8221; numbers_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_countdown_timer][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00123a&#8221; custom_padding=&#8221;||65px|||&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0) 0%|#000099 100%&#8221; custom_margin=&#8221;11px|auto||auto||&#8221; custom_padding=&#8221;34px|20px|34px|20px|true|true&#8221; custom_padding_tablet=&#8221;34px|30px|34px|30px|true|true&#8221; custom_padding_phone=&#8221;34px|30px|34px|30px|true|true&#8221; background_last_edited=&#8221;on|desktop&#8221; use_background_color_gradient_tablet=&#8221;on&#8221; use_background_color_gradient_phone=&#8221;on&#8221; background_color_gradient_direction_phone=&#8221;380deg&#8221; background_color_gradient_stops_tablet=&#8221;rgba(255,255,255,0) 0%|#2b1d72 100%&#8221; background_color_gradient_stops_phone=&#8221;rgba(255,255,255,0) 18%|#10008e 100%&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/mkt.estrategia.com\/concursos\/wp-content\/uploads\/sites\/2\/2024\/07\/30-dias-de-garantia-mais3-1.webp&#8221; title_text=&#8221;30-dias-de-garantia-mais3-1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;67%&#8221; max_width=&#8221;67%&#8221; custom_margin=&#8221;-6px||||false|false&#8221; custom_margin_tablet=&#8221;40px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; filter_hue_rotate=&#8221;233deg&#8221; filter_saturate=&#8221;113%&#8221; filter_brightness=&#8221;86%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text content_tablet=&#8221;<\/p>\n<h1><span style=%22color: #dba400;%22>O risco \u00e9 todo nosso!<\/span><\/h1>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h1><span style=%22color: #dba400;%22>O risco \u00e9 todo nosso!<\/span><\/h1>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;21px&#8221; header_font=&#8221;Poppins Medium||||||||&#8221; header_text_color=&#8221;#988eff&#8221; header_font_size=&#8221;32px&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;Poppins Medium|600|||||||&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;20px&#8221; header_2_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px||15px||false|false&#8221; custom_margin_tablet=&#8221;||3px|||&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;||0px|||&#8221; text_font_size_phone=&#8221;11px&#8221; header_font_size_tablet=&#8221;32px&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_align_tablet=&#8221;&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;22.5px&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><span style=\"color: #dba400;\">O risco \u00e9 todo nosso!<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_text content_tablet=&#8221;<\/p>\n<h2>Dentro de 30 dias, caso se arrependa da compra, por qualquer motivo, n\u00f3s devolvemos 100% do seu dinheiro!*<\/h2>\n<p>&#8221; content_phone=&#8221;<\/p>\n<h2 style=%22text-align: center;%22><span style=%22color: #ffffff;%22><strong>Garantia de 30 dias:<\/strong><\/span> teste nosso material e, se n\u00e3o estiver 100% satisfeito, receba seu dinheiro de volta!<\/h2>\n<p>&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins Regular||||||||&#8221; header_font=&#8221;Poppins Regular||||||||&#8221; header_2_font=&#8221;Poppins Regular||||||||&#8221; header_2_text_color=&#8221;#eaefff&#8221; header_2_font_size=&#8221;21.2px&#8221; header_2_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||||false|false&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;18px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;22.5px&#8221; header_2_font_size_phone=&#8221;18px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: left;\"><span style=\"font-weight: 400;\">Teste o material por 30 dias sem compromisso.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\"> Se n\u00e3o ficar satisfeito, devolvemos o seu dinheiro.<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#edd27b&#8221; text_font_size=&#8221;49px&#8221; text_line_height=&#8221;1.4em&#8221; header_font=&#8221;Roboto Regular||||||||&#8221; header_font_size=&#8221;73px&#8221; background_enable_color=&#8221;off&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;20px||||false|false&#8221; header_font_size_tablet=&#8221;73px&#8221; header_font_size_phone=&#8221;43px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; border_radii=&#8221;on|15px|15px|15px|15px&#8221; global_colors_info=&#8221;{}&#8221; max_width__hover_enabled=&#8221;on|desktop&#8221;]<\/p>\n<h1 style=\"text-align: left;\"><span style=\"color: #f8be26;\"><strong>FAQ: Tire suas d\u00favidas!<\/strong><\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_accordion _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_accordion_item title=&#8221;Quais s\u00e3o as formas de pagamento?&#8221; open=&#8221;on&#8221; open_toggle_text_color=&#8221;#000000&#8243; closed_toggle_text_color=&#8221;#edd27b&#8221; closed_toggle_background_color=&#8221;#061847&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;|||0px|false|false&#8221; custom_padding=&#8221;|||30px|false|false&#8221; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; toggle_font_size=&#8221;23px&#8221; closed_toggle_font=&#8221;|700|||||||&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">\u00a0Cart\u00e3o de cr\u00e9dito, pix ou boleto.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Como funciona a garantia de 30 dias?&#8221; open_toggle_text_color=&#8221;#000000&#8243; closed_toggle_text_color=&#8221;#edd27b&#8221; closed_toggle_background_color=&#8221;#061847&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;|||0px|false|false&#8221; custom_padding=&#8221;|||30px|false|false&#8221; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; toggle_font_size=&#8221;23px&#8221; closed_toggle_font=&#8221;|700|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Voc\u00ea pode cancelar em at\u00e9 30 dias e receber 100% do seu dinheiro de volta, se n\u00e3o tiver baixado mais de 200 conte\u00fados.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Existe limita\u00e7\u00e3o de acesso?&#8221; open_toggle_text_color=&#8221;#000000&#8243; closed_toggle_text_color=&#8221;#edd27b&#8221; closed_toggle_background_color=&#8221;#061847&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;|||0px|false|false&#8221; custom_padding=&#8221;|||30px|false|false&#8221; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; toggle_font_size=&#8221;23px&#8221; closed_toggle_font=&#8221;|700|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o. Voc\u00ea poder\u00e1 baixar e assistir a todo o material quantas vezes quiser.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Quando recebo acesso?&#8221; open_toggle_text_color=&#8221;#000000&#8243; closed_toggle_text_color=&#8221;#edd27b&#8221; closed_toggle_background_color=&#8221;#061847&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;|||0px|false|false&#8221; custom_padding=&#8221;|||30px|false|false&#8221; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; toggle_font_size=&#8221;23px&#8221; closed_toggle_font=&#8221;|700|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">\u00a0Assim que a matr\u00edcula for confirmada, voc\u00ea receber\u00e1 um e-mail com orienta\u00e7\u00f5es para acessar o material imediatamente.<\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;A plataforma \u00e9 segura?&#8221; open_toggle_text_color=&#8221;#000000&#8243; closed_toggle_text_color=&#8221;#edd27b&#8221; closed_toggle_background_color=&#8221;#061847&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;|||0px|false|false&#8221; custom_padding=&#8221;|||30px|false|false&#8221; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; toggle_font_size=&#8221;23px&#8221; closed_toggle_font=&#8221;|700|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Sim. Milhares de alunos j\u00e1 compraram pelo mesmo processo.<\/span><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][whatsapp_estrategia _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][whatsapp_item titulo=&#8221;D\u00favida? Fale com um de nossos consultores&#8221; link=&#8221;https:\/\/mais.red\/run\/nunca-mais-seja-demitido-consultores&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/whatsapp_item][\/whatsapp_estrategia][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EU VOU PERDER O MEU EMPREGO?Certamente, voc\u00ea j\u00e1 conviveu com essa d\u00favida. Mas, voc\u00ea n\u00e3o est\u00e1 sozinho \u2014 e uma nova oportunidade pode estar apenas come\u00e7ando. \u2611 No dia 8 de setembro de 2025, o Ita\u00fa Unibanco realizou desligamentos em funcion\u00e1rios em regime remoto ou h\u00edbrido, ap\u00f3s uma &#8220;revis\u00e3o criteriosa de condutas relacionadas ao trabalho [&hellip;]<\/p>\n","protected":false},"author":53,"featured_media":10,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-416452","page","type-page","status-publish","has-post-thumbnail","hentry","category-vendas"],"_links":{"self":[{"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/pages\/416452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/comments?post=416452"}],"version-history":[{"count":29,"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/pages\/416452\/revisions"}],"predecessor-version":[{"id":416574,"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/pages\/416452\/revisions\/416574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/media\/10"}],"wp:attachment":[{"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/media?parent=416452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/categories?post=416452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mkt.estrategia.com\/concursos\/wp-json\/wp\/v2\/tags?post=416452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}